{"id":404141,"date":"2023-04-12T06:39:27","date_gmt":"2023-04-12T09:39:27","guid":{"rendered":"https:\/\/www.naseprogram.org\/?page_id=404141"},"modified":"2024-03-25T07:06:21","modified_gmt":"2024-03-25T10:06:21","slug":"micrometeorites","status":"publish","type":"page","link":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/","title":{"rendered":"Micrometeorites"},"content":{"rendered":"\n<p>Micrometeorites are deposited on roofs and terraces or even remain suspended in the atmosphere for a long time, and fall together with rain or snow. The most recommended method to recover this material is to look for it in the gutters, which collect the material that is deposited on the roofs, or in the gutters of the streets or highways.<\/p>\n\n\n\n<p>These&nbsp;micrometeorites&nbsp;come directly from the matter that gave rise to the solar system. They are therefore about 4,500 million years old.<\/p>\n\n\n\n<div class=\"wp-block-getwid-tabs\" data-active-tab=\"0\"><ul class=\"wp-block-getwid-tabs__nav-links\"><\/ul>\n<div class=\"wp-block-getwid-tabs__nav-link\"><span class=\"wp-block-getwid-tabs__title-wrapper\"><a href=\"#\"><span class=\"wp-block-getwid-tabs__title\">Introductory material<\/span><\/a><\/span><\/div><div class=\"wp-block-getwid-tabs__tab-content-wrapper\"><div class=\"wp-block-getwid-tabs__tab-content\">\n<p><a href=\"https:\/\/docs.google.com\/document\/d\/1D1V6FkvAK_-qiKSIZaeHW4tqURkmAMWi\/edit#heading=h.gjdgxs\"><\/a><a href=\"https:\/\/www.naseprogram.org\/wp-content\/uploads\/sites\/10\/2023\/04\/micrometeoritos-eng-final-2-1-1.docx\">Introductory material that you have to read before performing the experiment<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-getwid-tabs__nav-link\"><span class=\"wp-block-getwid-tabs__title-wrapper\"><a href=\"#\"><span class=\"wp-block-getwid-tabs__title\">Material to send<\/span><\/a><\/span><\/div><div class=\"wp-block-getwid-tabs__tab-content-wrapper\"><div class=\"wp-block-getwid-tabs__tab-content\">\n<p><a href=\"https:\/\/www.naseprogram.org\/wp-content\/uploads\/sites\/10\/2023\/04\/micrometeoritos-para-enviar-eng-final.docx\">Material to send the participants in the project to newsletter.nase@gmail.com<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-getwid-tabs__nav-link\"><span class=\"wp-block-getwid-tabs__title-wrapper\"><a href=\"#\"><span class=\"wp-block-getwid-tabs__title\">Experiments<\/span><\/a><\/span><\/div><div class=\"wp-block-getwid-tabs__tab-content-wrapper\"><div class=\"wp-block-getwid-tabs__tab-content\">\n<p><strong>America<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/beeu\/\">Experiment 1<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jchm\/\">Experiment 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rgdc\/\">Experiment 3<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/knqd\/\">Experiment 4<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jdbc\/\">Experiment 5<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jlpi\/\">Experiment 6<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/hvdp\/\">Experiment 7<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ftfk\/\">Experiment 8<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lymv\/\">Experiment 9<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/axbs\/\">Experiment 10<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/iqlp\/\">Experiment 11<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/krkm\/\">Experiment 12<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dbng\/\">Experiment 13<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tyyz\/\">Experiment 14<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xnvb\/\">Experiment 15<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/yjjq\/\">Experiment 16<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tjcx\/\">Experiment 17<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tefc\/\">Experiment 18<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xnlm\/\">Experiment 19<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vflh\/\">Experiment 20<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sujo\/#p=1\">Experiment 21<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pjmk\/\">Experiment 22<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dbzo\/\">Experiment 23<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/nmhd\/\">Experiment 24<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/fkry\/\">Experiment 25<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jlmz\/\">Experiment 26<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/qrow\/\">Experiment 27<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wclm\/\">Experiment 28<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vfau\/\">Experiment 29<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Europe<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/yfok\/\">Experiment 1<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/qtfr\/#p=1\">Experiment 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/oxur\/\">Experiment 3<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/cmqn\/\">Experiment 4<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/oexg\/\">Experiment 5<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/owdy\/\">Experiment 6<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/evke\/\">Experiment 7<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pjet\/\">Experiment 8<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rfkl\/\">Experiment 9<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wzdk\/\">Experiment 10<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/apmu\/\">Experiment 11<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/yeyo\/\">Experiment 12<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/gjme\/\">Experiment 13<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/krpo\/\">Experiment 14<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/prny\/\">Experiment 15<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/emcc\/\">Experiment 16<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vfti\/\">Experiment 17<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/midm\/\">Experiment 18<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ybau\/\">Experiment 19<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vetu\/\">Experiment 20<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/uowr\/\">Experiment 21<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/soom\/\">Experiment 22<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sfwv\/\">Experiment 23<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lfqk\/\">Experiment 24<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lbbn\/\">Experiment 25<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/efth\/\">Experiment 26<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/qzwe\/\">Experiment 27<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/zeup\/\">Experiment 28<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/fcdp\/\">Experiment 29<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/nliz\/\">Experiment 30<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/zgsd\/\">Experiment 31<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/mmha\/\">Experiment 32<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/woqa\/\">Experiment 33<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/bfww\/\">Experiment 34<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dcvs\/\">Experiment 35<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dapf\/\">Experiment 36<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/riap\/\">Experiment 37<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jyzi\/\">Experiment 38<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/zrvm\/\">Experiment 39<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pykv\/\">Experiment 40<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/hxrr\/\">Experiment 41<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/txky\/\">Experiment 42<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dkbz\/\">Experiment 43<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/oces\/\">Experiment 44<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ljvo\/\">Experiment 45<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/mdti\/\">Experiment 46<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/inrz\/\">Experiment 47<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/zgba\/\">Experiment 48<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ndfe\/\">Experiment 49<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Africa<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tayd\/\">Experiment 1<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/moaj\/\">Experiment 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xbcv\/\">Experiment 3<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/hgvy\/\">Experiment 4<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sqyq\/\">Experiment 5<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/kpji\/\">Experiment 6<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ccrj\/\">Experiment 7<\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>Asia<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rlxa\/\">Experiment 1<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ulyk\/\">Experiment 2<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/gaew\/\">Experiment 3<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/hyga\/\">Experiment 4<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rtyi\/\">Experiment 5<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wnbv\/\">Experiment 6<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/uqvd\/\">Experiment 7<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ipva\/\">Experiment 8<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xrbk\/\">Experiment 9<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/htdo\/\">Experiment 10<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wcpy\/\">Experiment 11<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jtrt\/\">Experiment 12<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/prsy\/\">Experiment 13<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ekoq\/\">Experiment 14<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/puac\/\">Experiment 15<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/qyht\/\">Experiment 16<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wrta\/\">Experiment 17<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/qzgr\/\">Experiment 18<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jjpx\/\">Experiment 19<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/elnv\/\">Experiment 20<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xwnr\/\">Experiment 21<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ncxw\/\">Experiment 22<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/osmj\/\">Experiment 23<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sxpz\/\">Experiment 24<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/msrn\/\">Experiment 25<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/itlm\/\">Experiment 26<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xoto\/\">Experiment 27<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ixod\/\">Experiment 28<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/gbuw\/\">Experiment 29<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tzvw\/\">Experiment 30<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/furn\/\">Experiment 31<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sfvd\/\">Experiment 32<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/sfvd\/\">Experiment 33<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/jrwb\/\">Experiment 34<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dmbp\/\">Experiment 35<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/kftn\/\">Experiment 36<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pwcb\/\">Experiment 37<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/llfj\/\">Experiment 38<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/szcg\/\">Experiment 39<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/calu\/\">Experiment 40<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/tati\/\">Experiment 41<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lixd\/\">Experiment 42<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/acra\/\">Experiment 43<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/mnas\/\">Experiment 44<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/kzcp\/\">Experiment 45<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xbeo\/\">Experiment 46<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xdmq\/\">Experiment 47<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xcdj\/\">Experiment 48<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/fuoj\/\">Experiment 49<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wjcr\/\">Experiment 50<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/amfw\/\">Experiment 51<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/smbc\/\">Experiment 52<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ihbr\/\">Experiment 53<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/swzq\/\">Experiment 54<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/deij\/\">Experiment 55<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/iswj\/\">Experiment 56<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/knim\/\">Experiment 57<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vagm\/\">Experiment 58<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vpaq\/\">Experiment 59<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/njlm\/\">Experiment 60<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/onnj\/\">Experiment 61<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/kvvs\/\">Experiment 62<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/zpwk\/\">Experiment 63<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wgnt\/\">Experiment 64<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/yfhv\/\">Experiment 65<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pttb\/\">Experiment 66<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lddb\/\">Experiment 67<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/cuew\/\">Experiment 68<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dvzc\/\">Experiment 69<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pidr\/\">Experiment 70<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/vakl\/\">Experiment 71<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/fece\/\">Experiment 72<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/uwdp\/\">Experiment 73<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/kirh\/\">Experiment 74<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/wopr\/\">Experiment 75<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rcey\/\">Experiment 76<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ntfg\/\">Experiment 77<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ucps\/\">Experiment 78<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/mwcf\/\">Experiment 79<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/mwcf\/\">Experiment 80<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/orlq\/\">Experiment 81<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ardr\/\">Experiment 82<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/etul\/\">Experiment 83<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/lctp\/\">Experiment 84<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dgjc\/\">Experiment 85<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/edeq\/\">Experiment 86<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/dtdu\/\">Experiment 87<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/xzvt\/\">Experiment 88<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/bhzz\/\">Experiment 89<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/usbb\/\">Experiment 90<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/rxhx\/\">Experiment 91<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/pvtg\/\">Experiment 92<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/online.fliphtml5.com\/dtxgu\/ufjq\/\">Experiment 93<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-getwid-tabs__nav-link\"><span class=\"wp-block-getwid-tabs__title-wrapper\"><a href=\"#\"><span class=\"wp-block-getwid-tabs__title\">Summary<\/span><\/a><\/span><\/div><div class=\"wp-block-getwid-tabs__tab-content-wrapper\"><div class=\"wp-block-getwid-tabs__tab-content\">\n<p><a href=\"https:\/\/zenodo.org\/records\/10868140\">Book<\/a><\/p>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Micrometeorites are deposited on roofs and terraces or even remain suspended in the atmosphere for a long time, and fall together with rain or snow. The most recommended method to recover this material is to look for it in the gutters, which collect the material that is deposited on the roofs, or in the gutters &#8230; <a title=\"Micrometeorites\" class=\"read-more\" href=\"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/\" aria-label=\"More on Micrometeorites\">\u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/p>\n","protected":false},"author":13,"featured_media":0,"parent":272234,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-404141","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Micrometeorites - NASE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micrometeorites - NASE\" \/>\n<meta property=\"og:description\" content=\"Micrometeorites are deposited on roofs and terraces or even remain suspended in the atmosphere for a long time, and fall together with rain or snow. The most recommended method to recover this material is to look for it in the gutters, which collect the material that is deposited on the roofs, or in the gutters ... \u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/\" \/>\n<meta property=\"og:site_name\" content=\"NASE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-25T10:06:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/micrometeorites\\\/\",\"url\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/micrometeorites\\\/\",\"name\":\"Micrometeorites - NASE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#website\"},\"datePublished\":\"2023-04-12T09:39:27+00:00\",\"dateModified\":\"2024-03-25T10:06:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/micrometeorites\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/micrometeorites\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/micrometeorites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proiecte IAU\\\/UNESCO\",\"item\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/proiecte-iau-unesco\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Micrometeorites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/\",\"name\":\"NASE\",\"description\":\"Network for Astronomy School Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#organization\",\"name\":\"NASE\",\"url\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.naseprogram.org\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2021\\\/12\\\/naselogo.png\",\"contentUrl\":\"https:\\\/\\\/www.naseprogram.org\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2021\\\/12\\\/naselogo.png\",\"width\":234,\"height\":91,\"caption\":\"NASE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.naseprogram.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Micrometeorites - NASE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/","og_locale":"ar_AR","og_type":"article","og_title":"Micrometeorites - NASE","og_description":"Micrometeorites are deposited on roofs and terraces or even remain suspended in the atmosphere for a long time, and fall together with rain or snow. The most recommended method to recover this material is to look for it in the gutters, which collect the material that is deposited on the roofs, or in the gutters ... \u0625\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f","og_url":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/","og_site_name":"NASE","article_modified_time":"2024-03-25T10:06:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"3 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/","url":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/","name":"Micrometeorites - NASE","isPartOf":{"@id":"https:\/\/www.naseprogram.org\/ar\/#website"},"datePublished":"2023-04-12T09:39:27+00:00","dateModified":"2024-03-25T10:06:21+00:00","breadcrumb":{"@id":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/micrometeorites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naseprogram.org\/ar\/"},{"@type":"ListItem","position":2,"name":"Proiecte IAU\/UNESCO","item":"https:\/\/www.naseprogram.org\/ar\/proiecte-iau-unesco\/"},{"@type":"ListItem","position":3,"name":"Micrometeorites"}]},{"@type":"WebSite","@id":"https:\/\/www.naseprogram.org\/ar\/#website","url":"https:\/\/www.naseprogram.org\/ar\/","name":"NASE","description":"Network for Astronomy School Education","publisher":{"@id":"https:\/\/www.naseprogram.org\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naseprogram.org\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/www.naseprogram.org\/ar\/#organization","name":"NASE","url":"https:\/\/www.naseprogram.org\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/www.naseprogram.org\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.naseprogram.org\/wp-content\/uploads\/sites\/10\/2021\/12\/naselogo.png","contentUrl":"https:\/\/www.naseprogram.org\/wp-content\/uploads\/sites\/10\/2021\/12\/naselogo.png","width":234,"height":91,"caption":"NASE"},"image":{"@id":"https:\/\/www.naseprogram.org\/ar\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Willy Valentin","author_link":"https:\/\/www.naseprogram.org\/ar\/author\/willyvalen\/"},"uagb_comment_info":0,"uagb_excerpt":"Micrometeorites are deposited on roofs and terraces or even remain suspended in the atmosphere for a long time, and fall together with rain or snow. The most recommended method to recover this material is to look for it in the gutters, which collect the material that is deposited on the roofs, or in the gutters&hellip;","_links":{"self":[{"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/pages\/404141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/comments?post=404141"}],"version-history":[{"count":58,"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/pages\/404141\/revisions"}],"predecessor-version":[{"id":480387,"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/pages\/404141\/revisions\/480387"}],"up":[{"embeddable":true,"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/pages\/272234"}],"wp:attachment":[{"href":"https:\/\/www.naseprogram.org\/ar\/wp-json\/wp\/v2\/media?parent=404141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}